{"id":2923,"date":"2024-03-04T16:43:01","date_gmt":"2024-03-04T15:43:01","guid":{"rendered":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/dm-podcast\/maria-jose-catala-alcaldesa-de-valencia-en-el-acto-homenaje-a-los-bomberos-que-actuaron-en-campanar\/"},"modified":"2024-03-04T16:43:01","modified_gmt":"2024-03-04T15:43:01","slug":"maria-jose-catala-alcaldesa-de-valencia-en-el-acto-homenaje-a-los-bomberos-que-actuaron-en-campanar","status":"publish","type":"dm-podcast","link":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/dm-podcast\/maria-jose-catala-alcaldesa-de-valencia-en-el-acto-homenaje-a-los-bomberos-que-actuaron-en-campanar\/","title":{"rendered":"Mar\u00eda Jos\u00e9 Catal\u00e1 (alcaldesa de Val\u00e8ncia) en  el acto homenaje a los bomberos que actuaron en Campanar"},"featured_media":0,"template":"","meta":{"_acf_changed":false},"dm-programa":[7],"class_list":["post-2923","dm-podcast","type-dm-podcast","status-publish","hentry","dm-programa-podcast-radio-valencia-hora-14-comunitat-valenciana-2298"],"acf":{"url":"https:\/\/sdmedia.playser.cadenaser.com\/playser\/multimedia\/20243\/4\/1709553578168_1709553630_audio_128.mp3"},"_links":{"self":[{"href":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/dm-podcast\/2923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/dm-podcast"}],"about":[{"href":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/dm-podcast"}],"wp:attachment":[{"href":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=2923"}],"wp:term":[{"taxonomy":"dm-programa","embeddable":true,"href":"https:\/\/serbenidorm.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/dm-programa?post=2923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}